{"id":61438,"date":"2025-02-17T13:09:16","date_gmt":"2025-02-17T13:09:16","guid":{"rendered":"https:\/\/mexpo.pl?post_type=product&#038;p=61438"},"modified":"2025-02-17T14:49:57","modified_gmt":"2025-02-17T14:49:57","slug":"dch-12u-caricabatterie-a-12-tasche-per-il-modello-mguide-pellegrino-2","status":"publish","type":"product","link":"https:\/\/mexpo.eu\/it\/produkt\/dch-12u-caricabatterie-a-12-tasche-per-il-modello-mguide-pellegrino-2\/","title":{"rendered":"DCH-12U &#8211; Caricabatterie a 12 tasche per il modello mGuide Pellegrino 2"},"content":{"rendered":"<p>Caricabatterie leggero, eccezionalmente comodo, destinato a 12 dispositivi tourguide mGuide Pellegrino 2, con custodia nera.<br \/>\nLa custodia \u00e8 provvista di una chiusura lampo, di un attacco per il trasporto e di una tasca a rete interna. Dopo la collocazione dei ricevitori nelle tasche, la custodia mantiene uno spazio libero per gli accessori.<\/p>\n<p>Tempo di ricarica fino a 4,5h (da zero). Usare con pile ricaricabili AA NiMH di capacit\u00e0 non superiore a 2100mA. Dimensioni 32x12x14 cm.<\/p>\n<p>Rispetta l\u2019ambiente e risparmia:<br \/>\n&#8211; Rispetta l\u2019ambiente naturale \u2013 usa i caricabatterie e le pile ricaricabili al posto delle pile monouso!<br \/>\n&#8211; risparmia denaro \u2013 anche nella versione pi\u00f9 economica (Pellegrino 2), le pile monouso si esauriscono dopo circa 35 ore, mentre le pile ricaricabili saranno utilizzabili per anni!<\/p>\n<p>Il costo di 100 pile monouso AA per l&#8217;alimentazione di 1 kit Pellegrino 2 (50 ricevitori) \u00e8 pari a circa 90 PLN.<br \/>\nIl costo della ricarica di 100 pile ricaricabili \u00e8 inferiore a 1 PLN.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Caricabatterie estremamente comodo e leggero per dispositivi di guida turistica 12 mGuide Pellegrino 2 in una custodia nera. Tempo di ricarica fino a 4,5 ore (da zero). Compatibilit\u00e0 con mGuide Pellegrino 2.<\/p>\n","protected":false},"featured_media":48625,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[5221],"product_tag":[],"class_list":{"0":"post-61438","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-caricabatterie","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/mexpo.eu\/it\/wp-json\/wp\/v2\/product\/61438","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mexpo.eu\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mexpo.eu\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mexpo.eu\/it\/wp-json\/wp\/v2\/media\/48625"}],"wp:attachment":[{"href":"https:\/\/mexpo.eu\/it\/wp-json\/wp\/v2\/media?parent=61438"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mexpo.eu\/it\/wp-json\/wp\/v2\/product_brand?post=61438"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mexpo.eu\/it\/wp-json\/wp\/v2\/product_cat?post=61438"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mexpo.eu\/it\/wp-json\/wp\/v2\/product_tag?post=61438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}