{"id":62203,"date":"2025-02-17T13:20:03","date_gmt":"2025-02-17T13:20:03","guid":{"rendered":"https:\/\/mexpo.pl?post_type=product&#038;p=62203"},"modified":"2025-02-17T14:56:22","modified_gmt":"2025-02-17T14:56:22","slug":"cargador-okayo-wave-chg-24","status":"publish","type":"product","link":"https:\/\/mexpo.eu\/es\/produkt\/cargador-okayo-wave-chg-24\/","title":{"rendered":"Cargador Okayo WAVE CHG-24"},"content":{"rendered":"<p>Cargador colectivo dedicado en bolsa de transporte para 24 dispositivos. La bolsa tiene una &#8220;ventana&#8221; para una tarjeta de visita o una tarjeta con un contacto o logotipo de la empresa. El panel incorporado con pantalla LCD le permite seleccionar y sincronizar los canales del dispositivo en el cargador.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cargador colectivo dedicado en bolsa de transporte para 24 dispositivos. La bolsa tiene una &#8220;ventana&#8221; para una tarjeta de visita o una tarjeta con un contacto o logotipo de la empresa. El panel incorporado con pantalla LCD le permite seleccionar y sincronizar los canales del dispositivo en el cargador.<\/p>\n","protected":false},"featured_media":49754,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[5238],"product_tag":[],"class_list":{"0":"post-62203","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-cargadores","8":"first","9":"outofstock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/mexpo.eu\/es\/wp-json\/wp\/v2\/product\/62203","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mexpo.eu\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mexpo.eu\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mexpo.eu\/es\/wp-json\/wp\/v2\/media\/49754"}],"wp:attachment":[{"href":"https:\/\/mexpo.eu\/es\/wp-json\/wp\/v2\/media?parent=62203"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mexpo.eu\/es\/wp-json\/wp\/v2\/product_brand?post=62203"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mexpo.eu\/es\/wp-json\/wp\/v2\/product_cat?post=62203"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mexpo.eu\/es\/wp-json\/wp\/v2\/product_tag?post=62203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}